{"id":676757050,"count":3,"description":"","link":"https:\/\/melindaozel.com\/pt\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/","name":"aperto de l\u00e1bios","slug":"liptightener","taxonomy":"category","parent":676757178,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>lip tightener Archives - Face the FACS | Facial Expressions in Animation, AI, &amp; Behavior<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/melindaozel.com\/pt\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"lip tightener Archives\" \/>\n<meta property=\"og:url\" content=\"https:\/\/melindaozel.com\/pt\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/\" \/>\n<meta property=\"og:site_name\" content=\"Face the FACS | Facial Expressions in Animation, AI, &amp; Behavior\" \/>\n<meta property=\"og:image\" content=\"https:\/\/melindaozel.com\/wp-content\/uploads\/2020\/06\/face2-1024x1024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@melindaozel\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/melindaozel.com\\\/category\\\/facial-expressions\\\/action-units\\\/au23-2\\\/liptightener\\\/\",\"url\":\"https:\\\/\\\/melindaozel.com\\\/category\\\/facial-expressions\\\/action-units\\\/au23-2\\\/liptightener\\\/\",\"name\":\"lip tightener Archives - Face the FACS | Facial Expressions in Animation, AI, &amp; Behavior\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/melindaozel.com\\\/category\\\/facial-expressions\\\/action-units\\\/au23-2\\\/liptightener\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/melindaozel.com\\\/category\\\/facial-expressions\\\/action-units\\\/au23-2\\\/liptightener\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/melindaozel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"facial expressions\",\"item\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/category\\\/facial-expressions\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"action units (FACS AUs)\",\"item\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/category\\\/facial-expressions\\\/action-units\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"AU23\",\"item\":\"https:\\\/\\\/melindaozel.com\\\/category\\\/facial-expressions\\\/action-units\\\/au23-2\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"lip tightener\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/#website\",\"url\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/\",\"name\":\"Face the FACS\",\"description\":\"Facial Expressions in Art, Science, &amp; Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/#\\\/schema\\\/person\\\/81c6262e1bfca3c71960db5aee204e3f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/#\\\/schema\\\/person\\\/81c6262e1bfca3c71960db5aee204e3f\",\"name\":\"Melinda Ozel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1\",\"width\":225,\"height\":225,\"caption\":\"Melinda Ozel\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/melindaozel.com\",\"https:\\\/\\\/facebook.com\\\/facetheFACS\\\/\",\"https:\\\/\\\/instagram.com\\\/manicexpression\",\"https:\\\/\\\/linkedin.com\\\/in\\\/melindaozel\",\"https:\\\/\\\/pinterest.com\\\/melindaozel\\\/\",\"https:\\\/\\\/x.com\\\/melindaozel\",\"https:\\\/\\\/youtube.com\\\/@facetheFACS\"],\"knowsAbout\":[\"Facial Action Coding System (FACS)\",\"Facial Expression Tracking\",\"Facial Anatomy\",\"Facial Animation\",\"Digital Humans\",\"Audio-to-Expression\",\"Audio-to-Face\",\"Visemes\",\"Lipsync\"],\"jobTitle\":\"Facial Systems Expert, Expression Scientist\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"lip tightener Archives - Face the FACS | Facial Expressions in Animation, AI, &amp; Behavior","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/melindaozel.com\/pt\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/","og_locale":"pt_BR","og_type":"article","og_title":"lip tightener Archives","og_url":"https:\/\/melindaozel.com\/pt\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/","og_site_name":"Face the FACS | Facial Expressions in Animation, AI, &amp; Behavior","og_image":[{"width":1024,"height":1024,"url":"https:\/\/melindaozel.com\/wp-content\/uploads\/2020\/06\/face2-1024x1024.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@melindaozel","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/melindaozel.com\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/","url":"https:\/\/melindaozel.com\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/","name":"lip tightener Archives - Face the FACS | Express\u00f5es faciais em anima\u00e7\u00e3o, IA e comportamento","isPartOf":{"@id":"https:\/\/melindaozel.com\/zh\/#website"},"breadcrumb":{"@id":"https:\/\/melindaozel.com\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/#breadcrumb"},"inLanguage":"pt-BR"},{"@type":"BreadcrumbList","@id":"https:\/\/melindaozel.com\/category\/facial-expressions\/action-units\/au23-2\/liptightener\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/melindaozel.com\/"},{"@type":"ListItem","position":2,"name":"facial expressions","item":"https:\/\/melindaozel.com\/zh\/category\/facial-expressions\/"},{"@type":"ListItem","position":3,"name":"action units (FACS AUs)","item":"https:\/\/melindaozel.com\/zh\/category\/facial-expressions\/action-units\/"},{"@type":"ListItem","position":4,"name":"AU23","item":"https:\/\/melindaozel.com\/category\/facial-expressions\/action-units\/au23-2\/"},{"@type":"ListItem","position":5,"name":"lip tightener"}]},{"@type":"WebSite","@id":"https:\/\/melindaozel.com\/zh\/#website","url":"https:\/\/melindaozel.com\/zh\/","name":"Enfrentar o FACS","description":"Express\u00f5es faciais na arte, ci\u00eancia e tecnologia","publisher":{"@id":"https:\/\/melindaozel.com\/zh\/#\/schema\/person\/81c6262e1bfca3c71960db5aee204e3f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/melindaozel.com\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":["Person","Organization"],"@id":"https:\/\/melindaozel.com\/zh\/#\/schema\/person\/81c6262e1bfca3c71960db5aee204e3f","name":"Melinda Ozel","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1","url":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1","contentUrl":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1","width":225,"height":225,"caption":"Melinda Ozel"},"logo":{"@id":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1"},"sameAs":["https:\/\/melindaozel.com","https:\/\/facebook.com\/facetheFACS\/","https:\/\/instagram.com\/manicexpression","https:\/\/linkedin.com\/in\/melindaozel","https:\/\/pinterest.com\/melindaozel\/","https:\/\/x.com\/melindaozel","https:\/\/youtube.com\/@facetheFACS"],"knowsAbout":["Facial Action Coding System (FACS)","Facial Expression Tracking","Facial Anatomy","Facial Animation","Digital Humans","Audio-to-Expression","Audio-to-Face","Visemes","Lipsync"],"jobTitle":"Facial Systems Expert, Expression Scientist","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"_links":{"self":[{"href":"https:\/\/melindaozel.com\/pt\/wp-json\/wp\/v2\/categories\/676757050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melindaozel.com\/pt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/melindaozel.com\/pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/melindaozel.com\/pt\/wp-json\/wp\/v2\/categories\/676757178"}],"wp:post_type":[{"href":"https:\/\/melindaozel.com\/pt\/wp-json\/wp\/v2\/posts?categories=676757050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}