{"id":12876,"date":"2025-09-22T17:23:07","date_gmt":"2025-09-22T21:23:07","guid":{"rendered":"https:\/\/melindaozel.com\/?page_id=12876"},"modified":"2026-05-06T12:11:33","modified_gmt":"2026-05-06T16:11:33","slug":"all-about-lipsync-course","status":"publish","type":"page","link":"https:\/\/melindaozel.com\/ja\/all-about-lipsync-course\/","title":{"rendered":"\u30ea\u30c3\u30d7\u30b7\u30f3\u30af\u306b\u3064\u3044\u3066\u3059\u3079\u3066"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12876\" class=\"elementor elementor-12876\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d44b00c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d44b00c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9e4aa79\" data-id=\"9e4aa79\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-a2ae1bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a2ae1bd\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d9669bc\" data-id=\"d9669bc\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1234fcd elementor-widget elementor-widget-heading\" data-id=\"1234fcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">All About Lipsync<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93e7c8b elementor-widget elementor-widget-heading\" data-id=\"93e7c8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Decoding Speech Systems in Animation, Automation, and AI<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28e42d5 elementor-widget elementor-widget-text-editor\" data-id=\"28e42d5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Is your lipsync uncanny because you don&#8217;t know how speech works? Learn to diagnose core issues in automated systems and produce natural results. From linguistic foundations to modular FACS blendshape formulas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba84f40 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"ba84f40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"#pricing\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">How to get the course<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cf9a88b\" data-id=\"cf9a88b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3496428 elementor-widget elementor-widget-heading\" data-id=\"3496428\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">This Course Includes<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40178f7 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"40178f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A blueprint for building and QA-ing speech<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Lecture videos with Q&amp;A options<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">300+ slides of strategies, references, &amp; formulas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A 5-year access period to recordings<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Downloadable PDFs for personal reference<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21e7ff2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21e7ff2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-031f54d\" data-id=\"031f54d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-fd755fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fd755fb\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-db088e4\" data-id=\"db088e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e92735 elementor-widget elementor-widget-heading\" data-id=\"8e92735\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Skill Level<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1546f6 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e1546f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-chart-bar\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-90b4d7f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"90b4d7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Intermediate to expert<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-0de04ef\" data-id=\"0de04ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-08a2872 elementor-widget elementor-widget-heading\" data-id=\"08a2872\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Time to complete<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c42f198 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c42f198\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8e5ee2 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d8e5ee2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>2 hours<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2914be6\" data-id=\"2914be6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca5f827 elementor-widget elementor-widget-heading\" data-id=\"ca5f827\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sections<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d1c0326 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d1c0326\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-puzzle-piece\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M519.442 288.651c-41.519 0-59.5 31.593-82.058 31.593C377.409 320.244 432 144 432 144s-196.288 80-196.288-3.297c0-35.827 36.288-46.25 36.288-85.985C272 19.216 243.885 0 210.539 0c-34.654 0-66.366 18.891-66.366 56.346 0 41.364 31.711 59.277 31.711 81.75C175.885 207.719 0 166.758 0 166.758v333.237s178.635 41.047 178.635-28.662c0-22.473-40-40.107-40-81.471 0-37.456 29.25-56.346 63.577-56.346 33.673 0 61.788 19.216 61.788 54.717 0 39.735-36.288 50.158-36.288 85.985 0 60.803 129.675 25.73 181.23 25.73 0 0-34.725-120.101 25.827-120.101 35.962 0 46.423 36.152 86.308 36.152C556.712 416 576 387.99 576 354.443c0-34.199-18.962-65.792-56.558-65.792z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-618554f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"618554f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>8<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-a8c6283\" data-id=\"a8c6283\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f5bf16 elementor-widget elementor-widget-heading\" data-id=\"7f5bf16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Slides<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc78501 elementor-widget__width-initial elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dc78501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-tv\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M592 0H48A48 48 0 0 0 0 48v320a48 48 0 0 0 48 48h240v32H112a16 16 0 0 0-16 16v32a16 16 0 0 0 16 16h416a16 16 0 0 0 16-16v-32a16 16 0 0 0-16-16H352v-32h240a48 48 0 0 0 48-48V48a48 48 0 0 0-48-48zm-16 352H64V64h512z\"><\/path><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b3fac62 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b3fac62\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>300+<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c71e857 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c71e857\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-031ac5e\" data-id=\"031ac5e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c4922a0 elementor-hidden-mobile elementor-widget elementor-widget-image\" data-id=\"c4922a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"150\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?fit=900%2C150&amp;ssl=1\" class=\"attachment-large size-large wp-image-13343\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?w=1955&amp;ssl=1 1955w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?resize=300%2C50&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?resize=1024%2C171&amp;ssl=1 1024w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?resize=768%2C128&amp;ssl=1 768w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?resize=1536%2C256&amp;ssl=1 1536w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?resize=18%2C3&amp;ssl=1 18w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?resize=1320%2C220&amp;ssl=1 1320w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Melinda_Ozel_clients_2025.web_.webp?w=1800&amp;ssl=1 1800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a75fa2 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-image\" data-id=\"5a75fa2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"578\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/clients-mobile-2025.webp?fit=900%2C578&amp;ssl=1\" class=\"attachment-large size-large wp-image-12931\" alt=\"Logos of brands that Face the FACS has worked with: Industrial Light &amp; Magic, Epic Games, EA, Meta, Hyperreal, Blizzard, Netflix, The Mill\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/clients-mobile-2025.webp?w=983&amp;ssl=1 983w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/clients-mobile-2025.webp?resize=300%2C193&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/clients-mobile-2025.webp?resize=768%2C493&amp;ssl=1 768w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/clients-mobile-2025.webp?resize=18%2C12&amp;ssl=1 18w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-949bd0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"949bd0c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5796489\" data-id=\"5796489\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-510ce32 elementor-widget elementor-widget-spacer\" data-id=\"510ce32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-725533e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"725533e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db94e57\" data-id=\"db94e57\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d09c34f elementor-widget elementor-widget-heading\" data-id=\"d09c34f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About this course<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0cc7f7 elementor-widget elementor-widget-text-editor\" data-id=\"b0cc7f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>All About Lipsync is a comprehensive guide to speech mechanics. The course begins with articulation fundamentals and builds toward customizable, anatomy-driven FACS blendshape formulas. You\u2019ll learn which visual features are essential to each sound and how to leverage that information to develop in-house systems and strategies for high-fidelity performance refinement.<\/p><p>There is no one-size-fits-all approach to lipsync. Rather than relying on generic phoneme-to-viseme mappings, this course focuses on the underlying logic of speech and articulation, enabling you to adapt your approach to different rigs, styles, and performance contexts. Human speech is complex, and All About Lipsync equips you to work with that complexity through modular strategies that leave room for emotion, stylization, and situational nuance.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8b2189d elementor-widget elementor-widget-spacer\" data-id=\"8b2189d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86a5c34 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86a5c34\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8057f1c\" data-id=\"8057f1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b1c4e9 elementor-widget elementor-widget-heading\" data-id=\"4b1c4e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Intended audience<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d1ab88 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d1ab88\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a573fe0\" data-id=\"a573fe0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-05919d1 elementor-widget elementor-widget-accordion\" data-id=\"05919d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5831\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-5831\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Q: Who is the target audience for this course?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5831\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-5831\"><p><strong>A: <\/strong>This course is designed for animators, riggers, and engineers working on automated or generative speech animation who want to understand the linguistic and anatomical logic behind lipsync. If you&#8217;ve ever questioned a viseme chart, hit the limits of existing tools, or needed to build from first principles, All About Lipsync is your blueprint. Hand-key animators who want to go deeper than muscle memory will find it just as essential.<strong><br \/><\/strong><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-5832\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-5832\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Q: What experience level do you need?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-5832\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-5832\"><p>While no prior phonetics background is required, some familiarity with animated speech or FACS is recommended.<\/p><p><span style=\"text-decoration: underline;\">NOTE<\/span>: For the <em>Shape Building Ingredients<\/em> sections, prior FACS knowledge is helpful. You can supplement any knowledge gaps with my free <a href=\"https:\/\/melindaozel.com\/free-resources\/\" target=\"_blank\" rel=\"noopener\">FACS resources<\/a>, or reach out for a course bundle discount (<a href=\"https:\/\/melindaozel.com\/services\/lectures-training\/facs-cram-session\/\" target=\"_blank\" rel=\"noopener\">FACS Cram Session<\/a> + All About Lipsync).<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09688f5 elementor-widget elementor-widget-spacer\" data-id=\"09688f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f86f6be elementor-widget elementor-widget-heading\" data-id=\"f86f6be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">What you walk away with<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2b9841 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b2b9841\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">A foundation in phonetics and articulation mechanics<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Flexible FACS &amp; blendshape-based viseme building strategies<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Self-paced lecture videos with a 5-year access period<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Q&amp;A email support<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">300+ slides of viseme strategies, references, &amp; blendshape formulas<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Downloadable PDF slides to keep forever<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1795037 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1795037\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9cbb136\" data-id=\"9cbb136\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d66d9eb elementor-widget elementor-widget-spacer\" data-id=\"d66d9eb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bf88029 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bf88029\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e1ffcb1\" data-id=\"e1ffcb1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-254022f elementor-widget elementor-widget-heading\" data-id=\"254022f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A look inside the lecture<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5140592 elementor-widget elementor-widget-text-editor\" data-id=\"5140592\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\tOver 300 slides of charts, references, viseme strategies, and flexible blendshape formulas&#8230;\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-49866e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49866e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c97283a\" data-id=\"c97283a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7184ec elementor-widget elementor-widget-image\" data-id=\"e7184ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?fit=900%2C506&amp;ssl=1\" class=\"attachment-large size-large wp-image-12986\" alt=\"FACS and phonemes lecture slide\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?w=1920&amp;ssl=1 1920w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?resize=18%2C10&amp;ssl=1 18w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?resize=1320%2C743&amp;ssl=1 1320w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/Spectrum-of-widened-vowel-shapes-taken-from-moments-in-speech.webp?w=1800&amp;ssl=1 1800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-1f40106\" data-id=\"1f40106\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da05284 elementor-widget elementor-widget-image\" data-id=\"da05284\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"504\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?fit=900%2C504&amp;ssl=1\" class=\"attachment-large size-large wp-image-13722\" alt=\"Venn Diagram of visual phoneme classications\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?w=2338&amp;ssl=1 2338w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?resize=300%2C168&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?resize=1024%2C574&amp;ssl=1 1024w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?resize=768%2C430&amp;ssl=1 768w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?resize=1536%2C861&amp;ssl=1 1536w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?resize=2048%2C1148&amp;ssl=1 2048w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?resize=18%2C10&amp;ssl=1 18w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?resize=1320%2C740&amp;ssl=1 1320w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/phoneme-categorization-strategies-for-visemes.webp?w=1800&amp;ssl=1 1800w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\"><\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-2041d3c elementor-widget elementor-widget-text-editor\" data-id=\"2041d3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><em>Broaden your understanding of lipsync through linguistic foundations, anatomical breakdowns, and FACS-based formulas.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e05584c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e05584c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-572be94\" data-id=\"572be94\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41ef5be elementor-widget elementor-widget-menu-anchor\" data-id=\"41ef5be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-menu-anchor\" id=\"pricing\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fc19e7d elementor-widget elementor-widget-spacer\" data-id=\"fc19e7d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1b712f elementor-widget elementor-widget-heading\" data-id=\"c1b712f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">How to get the course<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b413151 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b413151\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-5c33d45\" data-id=\"5c33d45\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2197c99 elementor-widget elementor-widget-price-table\" data-id=\"2197c99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"price-table.default\">\n\t\t\t\t\t\n\t\t<div class=\"elementor-price-table\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__header\">\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-price-table__heading\">\n\t\t\t\t\t\tOn-Demand Lipsync Course\t\t\t\t\t\t<\/h3>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__subheading\">\n\t\t\t\t\t\t\tSelf-paced. Start today.\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"elementor-price-table__price\">\n\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__currency\">&#036;<\/span>\t\t\t\t\t\t\t\t\t<span class=\"elementor-price-table__integer-part\">\n\t\t\t\t\t\t695\t\t\t\t\t<\/span>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<ul class=\"elementor-price-table__features-list\">\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-96ddd1f\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tInstant-access 2-hour lecture + email Q&amp;A\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-df67896\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t300+ slides of strategies, references, &amp; formulas\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-a7b4d19\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t5-year access to recordings\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<li class=\"elementor-repeater-item-f85721b\">\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__feature-inner\">\n\t\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-check-circle\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119.033 8 8 119.033 8 256s111.033 248 248 248 248-111.033 248-248S392.967 8 256 8zm0 48c110.532 0 200 89.451 200 200 0 110.532-89.451 200-200 200-110.532 0-200-89.451-200-200 0-110.532 89.451-200 200-200m140.204 130.267l-22.536-22.718c-4.667-4.705-12.265-4.736-16.97-.068L215.346 303.697l-59.792-60.277c-4.667-4.705-12.265-4.736-16.97-.069l-22.719 22.536c-4.705 4.667-4.736 12.265-.068 16.971l90.781 91.516c4.667 4.705 12.265 4.736 16.97.068l172.589-171.204c4.704-4.668 4.734-12.266.067-16.971z\"><\/path><\/svg>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\tDownloadable PDFs to keep\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"elementor-price-table__footer\">\n\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-price-table__button elementor-button elementor-size-md\" href=\"https:\/\/melindaozel.com\/subscribe\/all-about-lipsync-video-lectures\/\">\n\t\t\t\t\t\t\tAccess the course\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-6008fdd e-flex e-con-boxed e-con e-parent\" data-id=\"6008fdd\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0dde807 elementor-widget elementor-widget-text-editor\" data-id=\"0dde807\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Looking for studio lectures? Check out my <span style=\"text-decoration: underline;\"><a href=\"https:\/\/melindaozel.com\/services\/lectures-training\/\">live, remote workshops for teams<\/a><\/span>.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d9aff95 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d9aff95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11a240c\" data-id=\"11a240c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c299ee1 elementor-widget elementor-widget-spacer\" data-id=\"c299ee1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-667ad9f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"667ad9f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f677e66\" data-id=\"f677e66\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7feaf9e elementor-widget elementor-widget-spacer\" data-id=\"7feaf9e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dd13f49 elementor-widget elementor-widget-heading\" data-id=\"dd13f49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Syllabus<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb05e3c elementor-widget elementor-widget-text-editor\" data-id=\"cb05e3c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>1 Lesson | 8 Sections<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9b29f5 elementor-widget elementor-widget-toggle\" data-id=\"b9b29f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1941\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1941\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Intro to basic phonetics<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1941\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1941\"><ul><li>What is phonetics?<\/li><li>What is a phoneme?<\/li><li>What is a grapheme?<\/li><li>What is a viseme?<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1942\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1942\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Intro to consonants, important features, & strategic viseme groupings<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1942\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1942\"><ul><li>What is a consonant?<\/li><li>Consonants classifications &amp; how to assess primary consonant features from IPA charts<\/li><li>What are the viseme categories for consonants?<\/li><li>Intro to the Core Viseme Principles<\/li><li>What consonants should we prioritize &amp; why?<\/li><li>How to leverage phonemic features to create variable phoneme-to-viseme groupings<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1943\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1943\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Viseme groups & blendshape ingredients <\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1943\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1943\"><ul><li>Core viseme groups<\/li><li>How to not confuse graphemes from phonemes<\/li><li>\u201cRules\u201d for each group<\/li><li>How to build each shape<\/li><li>How to NOT build each shape<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1944\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1944\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Intro to vowels, important features, & strategic viseme groupings<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1944\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1944\"><ul><li>What is a vowel?<\/li><li>Vowel classifications &amp; how to assess primary vowel features from IPA charts<\/li><li>What are the viseme categories for vowels?<\/li><li>What vowels should we prioritize &amp; why?<\/li><li>How to build rounded vowel shapes<\/li><li>How to build widened vowels shapes<\/li><li>How to build relaxed vowels shapes<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1945\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1945\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Integrating viseme strategies with emotional contexts<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1945\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1945\"><ul><li>Reshaping your views of emotional speech<\/li><li>FACS-based action unit formulas for surprise, fear, sadness, disgust, anger, &amp; happiness<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1946\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1946\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Critical FACS combinations for speech<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1946\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1946\"><ul><li>Breaking down rounding shape ingredients<\/li><li>Visual references and breakdowns of:<ul><li>lip funneler + upper lip raiser + lower lip depressor<\/li><li>lip pucker + lip funneler<\/li><li>lip pucker + lip cincher<\/li><\/ul><\/li><li>Lip presser &amp; other actions that assist in increasing lip compression<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1947\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1947\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">The importance of relative shape contrast<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1947\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1947\"><ul><li>Rounding vs. spreading neighbors<\/li><li>Stepping away from ideas of absolute position and embracing relative position thinking<\/li><li>Visual example walkthrough<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1948\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1948\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Speech variability case study<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1948\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1948\"><ul><li>Observing visual outcomes of various phonemes in different contexts<\/li><li>Biomechanical efficiency principles<\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fbc9cb1 elementor-widget elementor-widget-spacer\" data-id=\"fbc9cb1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6cf2dd3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6cf2dd3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c38474f\" data-id=\"c38474f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-706993b elementor-widget elementor-widget-spacer\" data-id=\"706993b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-499bb7f elementor-widget elementor-widget-heading\" data-id=\"499bb7f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">About the instructor<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7635029 elementor-widget elementor-widget-text-editor\" data-id=\"7635029\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Hi! I\u2019m Melinda, a consultant and educator on all things face-related. I specialize in facial expressions, FACS (Facial Action Coding System), and facial anatomy. My background in faces originated in academia, migrated to tech, and now lives in the space between art, science, and technology.<\/p><p>I apply my expression expertise to a range of industries (film, game, tech, etc.) and products\/media (Emoji, AR\/VR face tracking, AAA game characters, photoreal animals, AI, deepfake technologies, etc.). If it has a face, you\u2019re in the right place.<\/p><p><strong>Explore my multidisciplinary project history below.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5f4d1f elementor-widget elementor-widget-accordion\" data-id=\"c5f4d1f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2071\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2071\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Film & 3D Characters<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2071\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2071\"><ul><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"><em>Here<\/em> \u2013 AI Facial Expression Consultant with Metaphysic (film, credited)<\/span><\/li><li><em>Watch the Skies<\/em> &#8211; AI-based Lipsync Expert (film, credited)<\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"><em>Jane<\/em>, Apple+ TV \u2013 Primate Expression Consultant (show, credited)<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\"><em>Gigi &amp; Nate<\/em> \u2013 Primate Expression Consultant (film, uncredited)<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Notorious B.I.G. HyperModel by Hyperreal \u2013 Expression Researcher<\/span><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2072\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-2072\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">VR & Face Tracking Tech<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2072\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-2072\"><ul><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Meta Quest Pro, face tracking \u2013 Expression Researcher &amp; Expression Data Specialist<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">System and method for applying an expression to an avatar (patent 10970907) \u2013 Co-inventor<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Systems and methods for improving animation of computer-generated avatars (patent 11270487) \u2013 Co-inventor<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Systems and methods for improving animation of computer-generated avatars (patent 11468616) \u2013 Co-inventor<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Oculus LipSync \u2013 Expression Researcher<\/span><\/li><\/ul><p class=\"cvGsUA direction-ltr align-center para-style-body\">\u00a0<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-2073\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-2073\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><svg class=\"e-font-icon-svg e-fas-plus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H272V64c0-17.67-14.33-32-32-32h-32c-17.67 0-32 14.33-32 32v144H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h144v144c0 17.67 14.33 32 32 32h32c17.67 0 32-14.33 32-32V304h144c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><svg class=\"e-font-icon-svg e-fas-minus\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M416 208H32c-17.67 0-32 14.33-32 32v32c0 17.67 14.33 32 32 32h384c17.67 0 32-14.33 32-32v-32c0-17.67-14.33-32-32-32z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">Product Design<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-2073\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-2073\"><ul><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Facebook Care reaction \u2013 Emoji Expression Consultant<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Facebook Emoji Sets \u2013 Emoji Expression Consultant<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Facebook Newsfeed Reactions \u2013 Emoji Expression Consultant<\/span><\/li><li class=\"cvGsUA direction-ltr align-center para-style-body\"><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\">Facebook Feeling\/Activity \u2013 Emoji Expression Consultant<\/span><\/li><\/ul><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1402bf4 elementor-widget elementor-widget-spacer\" data-id=\"1402bf4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-501b7d6 elementor-widget elementor-widget-heading\" data-id=\"501b7d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">All About Lipsync testimonials<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7a62b8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7a62b8c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-981c665\" data-id=\"981c665\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8b9cfed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8b9cfed\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ffe439d\" data-id=\"ffe439d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-885f41f elementor-widget elementor-widget-image\" data-id=\"885f41f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2026\/04\/Stijn-Valkenborg-Larian.webp?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-image-15425\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2026\/04\/Stijn-Valkenborg-Larian.webp?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2026\/04\/Stijn-Valkenborg-Larian.webp?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2026\/04\/Stijn-Valkenborg-Larian.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2026\/04\/Stijn-Valkenborg-Larian.webp?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-44d9c86\" data-id=\"44d9c86\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-916812b elementor-widget elementor-widget-heading\" data-id=\"916812b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.linkedin.com\/in\/stijn-valkenborg-3340626\/\">Stijn Valkenborg\n<br>Senior Technical Animator at Larian Studios<\/a><\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-baef8cd elementor-widget elementor-widget-text-editor\" data-id=\"baef8cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>It&#8217;s clear that it&#8217;s difficult to narrow down lipsync and facial animation to some basic rules, but [Melinda] give[s] them anyway. First we learn the rules before trying to break them. The visual examples, especially on FACS combinations, are a highlight. It&#8217;s a very focused course that is useful immediately, no matter what level your knowledge about lipsync is.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e58f599\" data-id=\"e58f599\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-2b883e1 e-flex e-con-boxed e-con e-parent\" data-id=\"2b883e1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-781909f elementor-widget elementor-widget-spacer\" data-id=\"781909f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e986b0 elementor-widget elementor-widget-heading\" data-id=\"6e986b0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Studio testimonials (from other courses)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2b996f7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2b996f7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-88876d4\" data-id=\"88876d4\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-65157d8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65157d8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-632b051\" data-id=\"632b051\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c762738 elementor-widget elementor-widget-image\" data-id=\"c762738\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/mark-flanagan-testimonial.webp?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-image-11680\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/mark-flanagan-testimonial.webp?w=268&amp;ssl=1 268w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/mark-flanagan-testimonial.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/mark-flanagan-testimonial.webp?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-04c7234\" data-id=\"04c7234\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-91c25ea elementor-widget elementor-widget-heading\" data-id=\"91c25ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mark Flanagan\n<br>Animation Education &amp; Training Manager<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8646042 elementor-widget elementor-widget-heading\" data-id=\"8646042\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Workshops with Epic Games &amp; Netflix<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b39bd54 elementor-widget elementor-widget-text-editor\" data-id=\"b39bd54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>I&#8217;ve had the great privilege of working with Melinda at my last 2 companies, Netflix and Epic Games. I have no hesitation in recommending her to anyone wanting to increase their knowledge, understanding, and application of facial expressions, in particular FACS (Facial Action Coding System).<\/p><p>There is simply no expert in the subject who I know of with more passion, dedication and intellectual curiosity. She combines this with a talent for teaching, and a gift for explaining via personal demonstration.Whether as a consultant, or a lecturer the value that she brings to any company or project is extraordinary, and I&#8217;m certain that I will be working with her again in the future. If you need to know about FACS, she is the number 1 &#8220;Goto&#8221; person in the world!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-86722d6\" data-id=\"86722d6\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ae297b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ae297b3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-eddc078\" data-id=\"eddc078\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2715dec elementor-widget elementor-widget-image\" data-id=\"2715dec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/shannon-thomas-testimonial.webp?fit=300%2C300&amp;ssl=1\" class=\"attachment-medium size-medium wp-image-11682\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/shannon-thomas-testimonial.webp?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/shannon-thomas-testimonial.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/shannon-thomas-testimonial.webp?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ff944a6\" data-id=\"ff944a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6495737 elementor-widget elementor-widget-heading\" data-id=\"6495737\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Shannon Thomas\n<br> Artist Supervisor <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-782b85c elementor-widget elementor-widget-heading\" data-id=\"782b85c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Workshops with Blizzard<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa9a8d6 elementor-widget elementor-widget-text-editor\" data-id=\"aa9a8d6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Melinda Ozel\u2019s knowledge of FACS is exceptional, and her classes are the best I\u2019ve ever seen on this subject. Where she truly excels is the level at which she understands facial anatomy and expressions, how and why each shape fires, combines or breaks, but also what tone or emotion they are to convey. <span class=\"more-text\" style=\"display: none;\"><br \/>To me this makes her classes uniquely beneficial in helping animators, rigging TDs and modelers create the most accurate performances.<\/span><\/p><p>Of all the the classes I\u2019ve seen on this subject none have ever married the technical aspects with this level of artistic execution, nor explained it so clearly, enthusiastically and thoroughly as Melinda has. From the beginner level all the way to the most senior artists, I\u2019ve witnessed everyone learn and improve from her detailed instruction. If you are seeking to learn or level up your team, I cannot recommend her enough.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f43f3c3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f43f3c3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-81b052c\" data-id=\"81b052c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f173b30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f173b30\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-303d3e8\" data-id=\"303d3e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d285422 elementor-widget elementor-widget-image\" data-id=\"d285422\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/josh-dicarlo-insomniac.webp?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-image-11679\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/josh-dicarlo-insomniac.webp?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/josh-dicarlo-insomniac.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/josh-dicarlo-insomniac.webp?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-f6661e2\" data-id=\"f6661e2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d40461e elementor-widget elementor-widget-heading\" data-id=\"d40461e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Josh Dicarlo \n<br>Character Technology Director<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0892da elementor-widget elementor-widget-heading\" data-id=\"f0892da\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Workshop with Insomniac Games<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-560fd8e elementor-widget elementor-widget-text-editor\" data-id=\"560fd8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>I\u2019ve had the privilege of hosting one of Melinda\u2019s Studio talks for our character development teams at Insomniac Games and I can assure you will not be disappointed! Her talks are jam packed with goods for both the novice and the professional. Highly recommend checking this out.<\/p><p>Whether you\u2019re an animator trying to craft more believable performance, a character artist or TD trying to create more plausible characters or rigs, an ML engineer trying to qualitatively evaluate your research against its anatomical basis, or a supervisor \/ director trying to help your team squeeze every last bit of realism out of an on screen performance \u2013 there is something in this talk for you.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ab89d3\" data-id=\"3ab89d3\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-8c233fc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8c233fc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-c6d8cce\" data-id=\"c6d8cce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9344edb elementor-widget elementor-widget-image\" data-id=\"9344edb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/holly-price-testimonial.webp?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-image-11681\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/holly-price-testimonial.webp?w=300&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/holly-price-testimonial.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/holly-price-testimonial.webp?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-237776e\" data-id=\"237776e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce81f8f elementor-widget elementor-widget-heading\" data-id=\"ce81f8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Holly Price\n<br>Character TD <\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70c1773 elementor-widget elementor-widget-heading\" data-id=\"70c1773\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Workshop with undisclosed studio<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-f25e349 elementor-widget elementor-widget-text-editor\" data-id=\"f25e349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Melinda joined us for an incredible 2-hour FACS Cram session last month and it was one of the most informative training sessions I have ever attended! Melinda is highly skilled at presenting potentially complex information in an engaging and clear manner. Our team were left feeling educated and excited to delve deeper into FACS!<\/p><p>I can\u2019t recommend Melinda\u2019s presentation services, or plethora of exhaustive and in-depth information on her website highly enough. Don\u2019t hesitate to contact Melinda if you are looking for any FACS training \u2013 she is an absolute pleasure to work with and a huge asset to any team education!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cbfc43c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cbfc43c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db7edba\" data-id=\"db7edba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc86cf9 elementor-widget elementor-widget-spacer\" data-id=\"dc86cf9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93dc652 elementor-widget elementor-widget-heading\" data-id=\"93dc652\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Individual testimonials (from other courses)<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4c07b0e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c07b0e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-08e24cb\" data-id=\"08e24cb\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-281aaad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"281aaad\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-00770e4\" data-id=\"00770e4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0edcb64 elementor-widget elementor-widget-image\" data-id=\"0edcb64\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Derrick-Sesson.webp?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-image-13327\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Derrick-Sesson.webp?w=433&amp;ssl=1 433w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Derrick-Sesson.webp?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Derrick-Sesson.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Derrick-Sesson.webp?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-dec141a\" data-id=\"dec141a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b5bebac elementor-widget elementor-widget-heading\" data-id=\"b5bebac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Derrick Sesson\n<br>Senior Facial Artist<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a8dfc0 elementor-widget elementor-widget-text-editor\" data-id=\"6a8dfc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>This course was an extremely beneficial to my understanding of FACS. The in-depth exploration of primary shapes provided me with a deeper understanding of primary shapes and facial anatomy for my career as a facial artist in film and games. Melinda does an excellent job correcting common misconceptions, making complex concepts easier to grasp.<\/p><p>The diagrams and video examples were incredibly helpful, offering clear visual guidance that I could apply immediately. This course was a fantastic value for the cost, and it has significantly improved my ability to create more accurate and expressive facial shapes. Would highly recommend to anyone who\u2019s looking deepen their understanding of FACS.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3ac193c\" data-id=\"3ac193c\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b3ac05c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b3ac05c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-09640f0\" data-id=\"09640f0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7697219 elementor-widget elementor-widget-image\" data-id=\"7697219\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Quentin-Defrance.webp?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-image-13329\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Quentin-Defrance.webp?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Quentin-Defrance.webp?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Quentin-Defrance.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Quentin-Defrance.webp?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Quentin-Defrance.webp?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9fa941c\" data-id=\"9fa941c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-da98226 elementor-widget elementor-widget-heading\" data-id=\"da98226\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Quentin Defrance\n<br>Real-time Rigging Supervisor<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-c5bbe10 elementor-widget elementor-widget-text-editor\" data-id=\"c5bbe10\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>If you have any interest in getting up to speed with FACS and its terminology, I can&#8217;t recommend Melinda&#8217;s FACS Cram Session enough. It&#8217;s packed with details, schematics, anatomical references and actual real-life examples that you really can&#8217;t find elsewhere and it&#8217;s all presented in a very clean and compelling way. Definitely an essential resource for anyone trying to understand or emulate facial animation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1534550 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1534550\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e775968\" data-id=\"e775968\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e0f8122 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0f8122\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ffb619f\" data-id=\"ffb619f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-148da21 elementor-widget elementor-widget-image\" data-id=\"148da21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Steven-Ekholm.webp?resize=150%2C150&amp;ssl=1\" class=\"attachment-thumbnail size-thumbnail wp-image-13330\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Steven-Ekholm.webp?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Steven-Ekholm.webp?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Steven-Ekholm.webp?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Steven-Ekholm.webp?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/11\/Steven-Ekholm.webp?resize=12%2C12&amp;ssl=1 12w\" sizes=\"(max-width: 150px) 100vw, 150px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-68201d0\" data-id=\"68201d0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ccd208 elementor-widget elementor-widget-heading\" data-id=\"3ccd208\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Steven Ekholm \n<br>Senior Character Artist\u200b<\/h4>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-18d13e9 elementor-widget elementor-widget-text-editor\" data-id=\"18d13e9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Even after being recently laid off, I paid to participate in this class knowing I would learn a lot&#8230; and it was worth every penny. Melinda conveys information in a succinct, intelligent way that translates confusing elements into making perfect sense. With the added bounty of reference and resources she leaves with the attendees., it turned out to be one of those wonderful and rare experiences that really helped me to add to my expertise and inspired me to update my approach as a professional. Melinda is clearly an expert and a solid teacher, and I highly recommend learning from her.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-89f3675\" data-id=\"89f3675\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7809a59 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7809a59\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-03e6e18\" data-id=\"03e6e18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0fd256e elementor-widget elementor-widget-spacer\" data-id=\"0fd256e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-d7e79c7 e-flex e-con-boxed e-con e-parent\" data-id=\"d7e79c7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9dfd727 elementor-widget elementor-widget-text-editor\" data-id=\"9dfd727\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Start your lipsync journey today.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-693edd8 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"693edd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/melindaozel.com\/subscribe\/all-about-lipsync-video-lectures\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Get the course<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>All About Lipsync Decoding Speech Systems in Animation, Automation, and AI Is your lipsync uncanny because you don&#8217;t know how speech works? Learn to diagnose core issues in automated systems and produce natural results. From linguistic foundations to modular FACS blendshape formulas. How to get the course This Course Includes A blueprint for building and &#8230; <a title=\"\u30ea\u30c3\u30d7\u30b7\u30f3\u30af\u306b\u3064\u3044\u3066\u3059\u3079\u3066\" class=\"read-more\" href=\"https:\/\/melindaozel.com\/ja\/all-about-lipsync-course\/\" aria-label=\"\u30ea\u30c3\u30d7\u30b7\u30f3\u30af\u306e\u3059\u3079\u3066 \u306b\u3064\u3044\u3066\u3055\u3089\u306b\u8aad\u3080\">\u3082\u3063\u3068\u8aad\u3080<\/a><\/p>","protected":false},"author":60486633,"featured_media":12881,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_wpcom_ai_launchpad_about_page":false,"_wpcom_ai_launchpad_gallery_page":false,"_wpcom_ai_launchpad_contact_page":false,"_wpcom_ai_launchpad_events_page":false,"_wpcom_ai_launchpad_video_page":false,"_wpcom_ai_launchpad_portfolio_piece":false,"footnotes":""},"class_list":["post-12876","page","type-page","status-publish","has-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.4 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>All About Lipsync Course | Speech Mechanics for Animation &amp; AI<\/title>\n<meta name=\"description\" content=\"A lip sync course grounded in FACS, anatomy, and speech mechanics. Built for teams working on AI speech and animation systems.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/melindaozel.com\/ja\/all-about-lipsync-course\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"All About Lipsync Lecture\" \/>\n<meta property=\"og:description\" content=\"A crash course in English phonemes, visemes, and speech articulation for artists and researchers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/melindaozel.com\/ja\/all-about-lipsync-course\/\" \/>\n<meta property=\"og:site_name\" content=\"Face the FACS | Facial Expressions in Animation, AI, &amp; Behavior\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/facebook.com\/facetheFACS\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-06T16:11:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/melindaozel.com\/wp-content\/uploads\/2025\/09\/All-About-Lipsync-Class.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"2844\" \/>\n\t<meta property=\"og:image:height\" content=\"1584\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"All About Lipsync\" \/>\n<meta name=\"twitter:site\" content=\"@melindaozel\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"9\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/melindaozel.com\\\/all-about-lipsync-course\\\/\",\"url\":\"https:\\\/\\\/melindaozel.com\\\/all-about-lipsync-course\\\/\",\"name\":\"All About Lipsync Course | Speech Mechanics for Animation & AI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/melindaozel.com\\\/all-about-lipsync-course\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/melindaozel.com\\\/all-about-lipsync-course\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/All-About-Lipsync-Class.webp?fit=2844%2C1584&ssl=1\",\"datePublished\":\"2025-09-22T21:23:07+00:00\",\"dateModified\":\"2026-05-06T16:11:33+00:00\",\"description\":\"A lip sync course grounded in FACS, anatomy, and speech mechanics. Built for teams working on AI speech and animation systems.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/melindaozel.com\\\/all-about-lipsync-course\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/melindaozel.com\\\/all-about-lipsync-course\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/melindaozel.com\\\/all-about-lipsync-course\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/All-About-Lipsync-Class.webp?fit=2844%2C1584&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/All-About-Lipsync-Class.webp?fit=2844%2C1584&ssl=1\",\"width\":2844,\"height\":1584,\"caption\":\"lipsync class cover photo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/melindaozel.com\\\/all-about-lipsync-course\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/melindaozel.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"All About Lipsync\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/#website\",\"url\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/\",\"name\":\"Face the FACS\",\"description\":\"Facial Expressions in Art, Science, &amp; Technology\",\"publisher\":{\"@id\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/#\\\/schema\\\/person\\\/81c6262e1bfca3c71960db5aee204e3f\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/melindaozel.com\\\/zh\\\/#\\\/schema\\\/person\\\/81c6262e1bfca3c71960db5aee204e3f\",\"name\":\"Melinda Ozel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1\",\"width\":225,\"height\":225,\"caption\":\"Melinda Ozel\"},\"logo\":{\"@id\":\"https:\\\/\\\/i0.wp.com\\\/melindaozel.com\\\/wp-content\\\/uploads\\\/2025\\\/02\\\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1\"},\"sameAs\":[\"https:\\\/\\\/melindaozel.com\",\"https:\\\/\\\/facebook.com\\\/facetheFACS\\\/\",\"https:\\\/\\\/instagram.com\\\/manicexpression\",\"https:\\\/\\\/linkedin.com\\\/in\\\/melindaozel\",\"https:\\\/\\\/pinterest.com\\\/melindaozel\\\/\",\"https:\\\/\\\/x.com\\\/melindaozel\",\"https:\\\/\\\/youtube.com\\\/@facetheFACS\"],\"knowsAbout\":[\"Facial Action Coding System (FACS)\",\"Facial Expression Tracking\",\"Facial Anatomy\",\"Facial Animation\",\"Digital Humans\",\"Audio-to-Expression\",\"Audio-to-Face\",\"Visemes\",\"Lipsync\"],\"jobTitle\":\"Facial Systems Expert, Expression Scientist\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u30ea\u30c3\u30d7\u30b7\u30f3\u30af\u5b8c\u5168\u30de\u30b9\u30bf\u30fc\u8b1b\u5ea7 | \u30a2\u30cb\u30e1\u30fc\u30b7\u30e7\u30f3\uff06AI\u306e\u305f\u3081\u306e\u767a\u58f0\u30e1\u30ab\u30cb\u30af\u30b9","description":"FACS\uff08\u9854\u9762\u52d5\u4f5c\u5206\u6790\uff09\u3001\u89e3\u5256\u5b66\u3001\u767a\u58f0\u30e1\u30ab\u30cb\u30ba\u30e0\u306b\u57fa\u3065\u3044\u305f\u30ea\u30c3\u30d7\u30b7\u30f3\u30af\u8b1b\u5ea7\u3002AI\u97f3\u58f0\u30fb\u30a2\u30cb\u30e1\u30fc\u30b7\u30e7\u30f3\u30b7\u30b9\u30c6\u30e0\u958b\u767a\u30c1\u30fc\u30e0\u5411\u3051\u306b\u69cb\u7bc9\u3002.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/melindaozel.com\/ja\/all-about-lipsync-course\/","og_locale":"ja_JP","og_type":"article","og_title":"All About Lipsync Lecture","og_description":"A crash course in English phonemes, visemes, and speech articulation for artists and researchers.","og_url":"https:\/\/melindaozel.com\/ja\/all-about-lipsync-course\/","og_site_name":"Face the FACS | Facial Expressions in Animation, AI, &amp; Behavior","article_publisher":"https:\/\/facebook.com\/facetheFACS\/","article_modified_time":"2026-05-06T16:11:33+00:00","og_image":[{"width":2844,"height":1584,"url":"https:\/\/melindaozel.com\/wp-content\/uploads\/2025\/09\/All-About-Lipsync-Class.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_title":"All About Lipsync","twitter_site":"@melindaozel","twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"9\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/melindaozel.com\/all-about-lipsync-course\/","url":"https:\/\/melindaozel.com\/all-about-lipsync-course\/","name":"\u30ea\u30c3\u30d7\u30b7\u30f3\u30af\u5b8c\u5168\u30de\u30b9\u30bf\u30fc\u8b1b\u5ea7 | \u30a2\u30cb\u30e1\u30fc\u30b7\u30e7\u30f3\uff06AI\u306e\u305f\u3081\u306e\u767a\u58f0\u30e1\u30ab\u30cb\u30af\u30b9","isPartOf":{"@id":"https:\/\/melindaozel.com\/zh\/#website"},"primaryImageOfPage":{"@id":"https:\/\/melindaozel.com\/all-about-lipsync-course\/#primaryimage"},"image":{"@id":"https:\/\/melindaozel.com\/all-about-lipsync-course\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/All-About-Lipsync-Class.webp?fit=2844%2C1584&ssl=1","datePublished":"2025-09-22T21:23:07+00:00","dateModified":"2026-05-06T16:11:33+00:00","description":"FACS\uff08\u9854\u9762\u52d5\u4f5c\u5206\u6790\uff09\u3001\u89e3\u5256\u5b66\u3001\u767a\u58f0\u30e1\u30ab\u30cb\u30ba\u30e0\u306b\u57fa\u3065\u3044\u305f\u30ea\u30c3\u30d7\u30b7\u30f3\u30af\u8b1b\u5ea7\u3002AI\u97f3\u58f0\u30fb\u30a2\u30cb\u30e1\u30fc\u30b7\u30e7\u30f3\u30b7\u30b9\u30c6\u30e0\u958b\u767a\u30c1\u30fc\u30e0\u5411\u3051\u306b\u69cb\u7bc9\u3002.","breadcrumb":{"@id":"https:\/\/melindaozel.com\/all-about-lipsync-course\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/melindaozel.com\/all-about-lipsync-course\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/melindaozel.com\/all-about-lipsync-course\/#primaryimage","url":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/All-About-Lipsync-Class.webp?fit=2844%2C1584&ssl=1","contentUrl":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/09\/All-About-Lipsync-Class.webp?fit=2844%2C1584&ssl=1","width":2844,"height":1584,"caption":"lipsync class cover photo"},{"@type":"BreadcrumbList","@id":"https:\/\/melindaozel.com\/all-about-lipsync-course\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/melindaozel.com\/"},{"@type":"ListItem","position":2,"name":"All About Lipsync"}]},{"@type":"WebSite","@id":"https:\/\/melindaozel.com\/zh\/#website","url":"https:\/\/melindaozel.com\/zh\/","name":"FACS\u3068\u5411\u304d\u5408\u3046","description":"\u82b8\u8853\u30fb\u79d1\u5b66\u30fb\u6280\u8853\u306b\u304a\u3051\u308b\u8868\u60c5\u8868\u73fe","publisher":{"@id":"https:\/\/melindaozel.com\/zh\/#\/schema\/person\/81c6262e1bfca3c71960db5aee204e3f"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/melindaozel.com\/zh\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":["Person","Organization"],"@id":"https:\/\/melindaozel.com\/zh\/#\/schema\/person\/81c6262e1bfca3c71960db5aee204e3f","name":"\u30e1\u30ea\u30f3\u30c0\u30fb\u30aa\u30bc\u30eb","image":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1","url":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1","contentUrl":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1","width":225,"height":225,"caption":"Melinda Ozel"},"logo":{"@id":"https:\/\/i0.wp.com\/melindaozel.com\/wp-content\/uploads\/2025\/02\/face-the-FACS-eye-mouth-logo-pixel.webp?fit=225%2C225&ssl=1"},"sameAs":["https:\/\/melindaozel.com","https:\/\/facebook.com\/facetheFACS\/","https:\/\/instagram.com\/manicexpression","https:\/\/linkedin.com\/in\/melindaozel","https:\/\/pinterest.com\/melindaozel\/","https:\/\/x.com\/melindaozel","https:\/\/youtube.com\/@facetheFACS"],"knowsAbout":["Facial Action Coding System (FACS)","Facial Expression Tracking","Facial Anatomy","Facial Animation","Digital Humans","Audio-to-Expression","Audio-to-Face","Visemes","Lipsync"],"jobTitle":"Facial Systems Expert, Expression Scientist","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/pages\/12876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/users\/60486633"}],"replies":[{"embeddable":true,"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/comments?post=12876"}],"version-history":[{"count":94,"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/pages\/12876\/revisions"}],"predecessor-version":[{"id":15534,"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/pages\/12876\/revisions\/15534"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/media\/12881"}],"wp:attachment":[{"href":"https:\/\/melindaozel.com\/ja\/wp-json\/wp\/v2\/media?parent=12876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}